{"id":459,"date":"2020-11-10T15:16:32","date_gmt":"2020-11-10T15:16:32","guid":{"rendered":"http:\/\/ekoexport.com\/?p=459"},"modified":"2020-11-10T15:20:21","modified_gmt":"2020-11-10T15:20:21","slug":"linia-do-selektywnego-mieszania-mikrosfer","status":"publish","type":"post","link":"http:\/\/ekoexport.com\/en\/linia-do-selektywnego-mieszania-mikrosfer\/","title":{"rendered":"Linia do selektywnego mieszania mikrosfer"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"459\" class=\"elementor elementor-459\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-12bed68 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"12bed68\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6590564\" data-id=\"6590564\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf4b619 elementor-widget elementor-widget-text-editor\" data-id=\"bf4b619\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Na rynku mikrosfer obserwuje si\u0119 dwa wyra\u017ane trendy.<\/p><p>Z jednej strony stale rosn\u0105 wymagania klient\u00f3w w zakresie jako\u015bci mikrosfery, a w szczeg\u00f3lno\u015bci jej powtarzalno\u015bci. Zjawisko to jest szczeg\u00f3lnie widoczne w przypadku zastosowa\u0144 hi-tech, w kt\u00f3rych produkcja wyrob\u00f3w ko\u0144cowych odbywa si\u0119 w spos\u00f3b zautomatyzowany, a nawet najmniejsza odchy\u0142ka od oczekiwanej jako\u015bci mo\u017ce spowodowa\u0107 awari\u0119 linii klienta ko\u0144cowego. Wym\u00f3g powtarzalno\u015bci dotyczy zar\u00f3wno produkt\u00f3w pakowanych do big-bag\u00f3w, jak r\u00f3wnie\u017c do work\u00f3w papierowych. <br \/>Przemys\u0142 farb i lakier\u00f3w, produkty wykorzystuj\u0105ce mikrosfer\u0119 kierowane na rynki konsumenckie czy zaawansowane zastosowania ogniotrwa\u0142e wyznaczaj\u0105 ten trend.<\/p><p>Drugi trend zwi\u0105zany jest z naturalnymi cechami mikrosfery. B\u0119d\u0105c produktem ubocznym, jako\u015b\u0107 surowca jest zmienna i producenci mikrosfery maj\u0105 niewielki wp\u0142yw na materia\u0142 produkowany przez elektrowni\u0119. Dodatkowo klimat geopolityczny oraz zak\u0142\u00f3cenia globalnej gospodarki spowodowane przez Covid-19 wprowadzaj\u0105 dodatkowy poziom nieprzewidywalno\u015bci.<\/p><p>Zestawienie tych przeciwstawnych trend\u00f3w powoduje du\u017c\u0105 presj\u0119 na producent\u00f3w mikrosfery. Odpowiedz\u0105 Eko Export na te trendy jest konsekwentna, d\u0142ugofalowa polityka inwestowania w najnowsze technologie. Stale powi\u0119kszana przewaga technologiczna jest podstaw\u0105 pozyskiwania najbardziej atrakcyjnych kontrakt\u00f3w.<\/p><p>Najnowsza linia selektywnego mieszania mikrosfer uruchomiona w centrali sp\u00f3\u0142ki w Bielsku-Bia\u0142ej jest kluczowym elementem realizacji tej strategii. Dzi\u0119ki pe\u0142nemu opomiarowaniu oraz automatyzacji ca\u0142ego procesu mo\u017cliwe jest kontrolowanie jako\u015bci i sterowanie procesem mieszania mikrosfer w trybie ci\u0105g\u0142ym, a nie w oparciu o poszczeg\u00f3lne partie. Efektem jest powtarzalna, wysoka jako\u015b\u0107. Ze wzgl\u0119du na niejednorodny charakter mikrosfery, takie rozwi\u0105zanie pozwala na precyzyjne utrzymanie zgodno\u015bci produktu ko\u0144cowego ze specyfikacj\u0105 klienta. Wed\u0142ug wiedzy sp\u00f3\u0142ki oraz rozm\u00f3w z klientami, takiej technologii i takich mo\u017cliwo\u015bci nie ma \u017caden inny zak\u0142ad produkuj\u0105cy mikrosfer\u0119 na \u015bwiecie. Niespotykana dotychczas jako\u015b\u0107 i powtarzalno\u015b\u0107 mikrosfery poszerza mo\u017cliwo\u015bci zastosowania jej we wra\u017cliwych segmentach rynku obj\u0119tych embargiem informacyjnym.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-63b3cdf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"63b3cdf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aa1528d\" data-id=\"aa1528d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-55a04b5 elementor-widget elementor-widget-video\" data-id=\"55a04b5\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=eHETqu6xVd8&amp;feature=youtu.be&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-534d333\" data-id=\"534d333\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70c15a3 elementor-widget elementor-widget-video\" data-id=\"70c15a3\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=MR4Wp5BgWWM&amp;feature=youtu.be&amp;ab_channel=KatarzynaKarnecka&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-67c37eb elementor-widget elementor-widget-text-editor\" data-id=\"67c37eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Najnowsza linia technologiczna powsta\u0142a w \u015bcis\u0142ej wsp\u00f3\u0142pracy z kluczowymi klientami Eko Export, kt\u00f3rych zespo\u0142y laboratoryjne utrzymuj\u0105 sta\u0142y kontakt z laboratorium sp\u00f3\u0142ki. Efekty wsp\u00f3lnych prac rozwojowych s\u0105 wyra\u017anie widoczne w postaci atrakcyjnych zam\u00f3wie\u0144 pozyskiwanych przez Eko Export.<\/p><p>Dope\u0142nieniem nowej linii do selektywnego mieszania mikrosfer jest opracowany przez Eko Export i wdro\u017cony w sp\u00f3\u0142ce c\u00f3rce EKO Sphere KZ oraz u kluczowego partnera kazachskiego tr\u00f3jstopniowy system zarz\u0105dzania jako\u015bci\u0105 3Q obejmuj\u0105cy \u015bcis\u0142y nadz\u00f3r nad parametrami zrzutu surowca do laguny, zasady wst\u0119pnego przygotowania p\u00f3\u0142produktu do produkcji mikrosfery oraz przetwarzania ko\u0144cowego realizowanego przez zesp\u00f3\u0142 innowacyjnych linii technologicznych w Bielsku-Bia\u0142ej.<\/p><p>Zarz\u0105d Eko Export jest przekonany, i\u017c nowa linia technologiczna pozwoli sp\u00f3\u0142ce na przekszta\u0142cenie sytuacji kryzysu globalnego zwi\u0105zanego z Covid-19 w unikaln\u0105 szans\u0119 rozwoju i przeniesienia sp\u00f3\u0142ki na wy\u017cszy poziom.<br \/><br \/><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4b27cc4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4b27cc4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ac86f63\" data-id=\"ac86f63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e76d200 elementor-widget elementor-widget-video\" data-id=\"e76d200\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=xvbUvgl0y7Y&amp;feature=youtu.be&amp;ab_channel=KatarzynaKarnecka&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Na rynku mikrosfer obserwuje si\u0119 dwa wyra\u017ane trendy. Z jednej strony stale rosn\u0105 wymagania klient\u00f3w w zakresie jako\u015bci mikrosfery, a w szczeg\u00f3lno\u015bci jej powtarzalno\u015bci. Zjawisko to jest szczeg\u00f3lnie widoczne w przypadku zastosowa\u0144 hi-tech, w kt\u00f3rych produkcja wyrob\u00f3w ko\u0144cowych odbywa si\u0119 w spos\u00f3b zautomatyzowany, a nawet najmniejsza odchy\u0142ka od oczekiwanej jako\u015bci mo\u017ce spowodowa\u0107 awari\u0119 linii klienta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"0","ocean_second_sidebar":"0","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"0","ocean_custom_header_template":"0","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"0","ocean_menu_typo_font_family":"0","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"0","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"off","ocean_gallery_id":[]},"categories":[8],"tags":[],"_links":{"self":[{"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/posts\/459"}],"collection":[{"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/comments?post=459"}],"version-history":[{"count":5,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/posts\/459\/revisions"}],"predecessor-version":[{"id":469,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/posts\/459\/revisions\/469"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/media\/439"}],"wp:attachment":[{"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/media?parent=459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/categories?post=459"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/ekoexport.com\/en\/wp-json\/wp\/v2\/tags?post=459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}